{"id":4941,"date":"2016-11-30T10:35:05","date_gmt":"2016-11-30T10:35:05","guid":{"rendered":"http:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg"},"modified":"2016-11-30T10:35:05","modified_gmt":"2016-11-30T10:35:05","slug":"olympus-digital-camera-4","status":"inherit","type":"attachment","link":"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/","title":{"rendered":""},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-4941","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>~ Boja Acad\u00e8mia Familiar<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"~ Boja Acad\u00e8mia Familiar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Boja Acad\u00e8mia Familiar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocaAcademiaFamiliar\" \/>\n<meta property=\"og:image\" content=\"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/\",\"url\":\"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/\",\"name\":\"~ Boja Acad\u00e8mia Familiar\",\"isPartOf\":{\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#website\"},\"datePublished\":\"2016-11-30T10:35:05+00:00\",\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#website\",\"url\":\"https:\/\/locaacademiafamiliar.com\/ca\/\",\"name\":\"Boja Acad\u00e8mia Familiar\",\"description\":\"El blog de crianza con el que pap\u00e1s y mam\u00e1s salen mejor preparados para su rutina familiar diaria\",\"publisher\":{\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/locaacademiafamiliar.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#organization\",\"name\":\"LocaAcademiaFamiliar.com\",\"url\":\"https:\/\/locaacademiafamiliar.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg\",\"contentUrl\":\"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg\",\"width\":960,\"height\":960,\"caption\":\"LocaAcademiaFamiliar.com\"},\"image\":{\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LocaAcademiaFamiliar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"~ Boja Acad\u00e8mia Familiar","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"~ Boja Acad\u00e8mia Familiar","og_url":"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/","og_site_name":"Boja Acad\u00e8mia Familiar","article_publisher":"https:\/\/www.facebook.com\/LocaAcademiaFamiliar","og_image":[{"width":960,"height":1280,"url":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/","url":"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/","name":"~ Boja Acad\u00e8mia Familiar","isPartOf":{"@id":"https:\/\/locaacademiafamiliar.com\/ca\/#website"},"datePublished":"2016-11-30T10:35:05+00:00","inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/"]}]},{"@type":"WebSite","@id":"https:\/\/locaacademiafamiliar.com\/ca\/#website","url":"https:\/\/locaacademiafamiliar.com\/ca\/","name":"Boja Acad\u00e8mia Familiar","description":"El blog de crianza con el que pap\u00e1s y mam\u00e1s salen mejor preparados para su rutina familiar diaria","publisher":{"@id":"https:\/\/locaacademiafamiliar.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/locaacademiafamiliar.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/locaacademiafamiliar.com\/ca\/#organization","name":"LocaAcademiaFamiliar.com","url":"https:\/\/locaacademiafamiliar.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg","contentUrl":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg","width":960,"height":960,"caption":"LocaAcademiaFamiliar.com"},"image":{"@id":"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocaAcademiaFamiliar"]}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?ssl=1\"><img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=225%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"(max-width: 225px) 100vw, 225px\" data-attachment-id=\"4941\" data-permalink=\"https:\/\/locaacademiafamiliar.com\/ca\/olympus-digital-camera-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=960%2C1280&amp;ssl=1\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;TG-2&quot;,&quot;caption&quot;:&quot;OLYMPUS DIGITAL CAMERA&quot;,&quot;created_timestamp&quot;:&quot;1439122193&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;OLYMPUS DIGITAL CAMERA&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=768%2C1024&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div class=\"mh-excerpt\"><\/div>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":1280,"file":"2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg","sizes":{"thumbnail":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=225%2C300&ssl=1"},"medium_large":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=768%2C1024&ssl=1"},"large":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=768%2C1024&ssl=1"},"mh-magazine-slider":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-960x438.jpg","width":960,"height":438,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=960%2C438&ssl=1"},"mh-magazine-content":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-678x381.jpg","width":678,"height":381,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=678%2C381&ssl=1"},"mh-magazine-large":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-678x509.jpg","width":678,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=678%2C509&ssl=1"},"mh-magazine-medium":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=326%2C245&ssl=1"},"mh-magazine-small":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?resize=80%2C60&ssl=1"},"full":{"file":"Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=960%2C1280&ssl=1","width":960,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg?fit=960%2C1280&ssl=1"}},"image_meta":{"aperture":"8","credit":"","camera":"TG-2","caption":"OLYMPUS DIGITAL CAMERA","created_timestamp":"1439122193","copyright":"","focal_length":"4.5","iso":"200","shutter_speed":"0.005","title":"OLYMPUS DIGITAL CAMERA","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/Escapada_Solsona_Hotel_Vella_Farga30-2.jpg","_links":{"self":[{"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/media\/4941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/comments?post=4941"}]}}