{"id":4944,"date":"2016-11-30T10:37:01","date_gmt":"2016-11-30T10:37:01","guid":{"rendered":"http:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg"},"modified":"2016-11-30T10:37:01","modified_gmt":"2016-11-30T10:37:01","slug":"can-cuch-hotel-montseny-13","status":"inherit","type":"attachment","link":"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/","title":{"rendered":"can-cuch-hotel-montseny-13"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-4944","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>can-cuch-hotel-montseny-13 ~ Boja Acad\u00e8mia Familiar<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"can-cuch-hotel-montseny-13 ~ Boja Acad\u00e8mia Familiar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Boja Acad\u00e8mia Familiar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocaAcademiaFamiliar\" \/>\n<meta property=\"og:image\" content=\"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/\",\"url\":\"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/\",\"name\":\"can-cuch-hotel-montseny-13 ~ Boja Acad\u00e8mia Familiar\",\"isPartOf\":{\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#website\"},\"datePublished\":\"2016-11-30T10:37:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/locaacademiafamiliar.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"can-cuch-hotel-montseny-13\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#website\",\"url\":\"https:\/\/locaacademiafamiliar.com\/ca\/\",\"name\":\"Boja Acad\u00e8mia Familiar\",\"description\":\"El blog de crianza con el que pap\u00e1s y mam\u00e1s salen mejor preparados para su rutina familiar diaria\",\"publisher\":{\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/locaacademiafamiliar.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#organization\",\"name\":\"LocaAcademiaFamiliar.com\",\"url\":\"https:\/\/locaacademiafamiliar.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg\",\"contentUrl\":\"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg\",\"width\":960,\"height\":960,\"caption\":\"LocaAcademiaFamiliar.com\"},\"image\":{\"@id\":\"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LocaAcademiaFamiliar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"can-cuch-hotel-montseny-13 ~ Boja Acad\u00e8mia Familiar","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"can-cuch-hotel-montseny-13 ~ Boja Acad\u00e8mia Familiar","og_url":"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/","og_site_name":"Boja Acad\u00e8mia Familiar","article_publisher":"https:\/\/www.facebook.com\/LocaAcademiaFamiliar","og_image":[{"width":950,"height":713,"url":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/","url":"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/","name":"can-cuch-hotel-montseny-13 ~ Boja Acad\u00e8mia Familiar","isPartOf":{"@id":"https:\/\/locaacademiafamiliar.com\/ca\/#website"},"datePublished":"2016-11-30T10:37:01+00:00","breadcrumb":{"@id":"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/locaacademiafamiliar.com\/ca\/"},{"@type":"ListItem","position":2,"name":"can-cuch-hotel-montseny-13"}]},{"@type":"WebSite","@id":"https:\/\/locaacademiafamiliar.com\/ca\/#website","url":"https:\/\/locaacademiafamiliar.com\/ca\/","name":"Boja Acad\u00e8mia Familiar","description":"El blog de crianza con el que pap\u00e1s y mam\u00e1s salen mejor preparados para su rutina familiar diaria","publisher":{"@id":"https:\/\/locaacademiafamiliar.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/locaacademiafamiliar.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/locaacademiafamiliar.com\/ca\/#organization","name":"LocaAcademiaFamiliar.com","url":"https:\/\/locaacademiafamiliar.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg","contentUrl":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2020\/01\/logo-loca-academia-familiar.jpg","width":960,"height":960,"caption":"LocaAcademiaFamiliar.com"},"image":{"@id":"https:\/\/locaacademiafamiliar.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocaAcademiaFamiliar"]}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?ssl=1\"><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?w=950&amp;ssl=1 950w, https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=678%2C509&amp;ssl=1 678w, https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=326%2C245&amp;ssl=1 326w, https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=80%2C60&amp;ssl=1 80w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"4944\" data-permalink=\"https:\/\/locaacademiafamiliar.com\/ca\/can-cuch-hotel-montseny-13\/\" data-orig-file=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?fit=950%2C713&amp;ssl=1\" data-orig-size=\"950,713\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 5&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1395514843&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.12&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"can-cuch-hotel-montseny-13\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?fit=950%2C713&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div class=\"mh-excerpt\"><\/div>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":950,"height":713,"file":"2016\/11\/can-cuch-hotel-montseny-13.jpg","sizes":{"thumbnail":{"file":"can-cuch-hotel-montseny-13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"can-cuch-hotel-montseny-13-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"can-cuch-hotel-montseny-13-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?fit=768%2C576&ssl=1"},"mh-magazine-slider":{"file":"can-cuch-hotel-montseny-13-950x438.jpg","width":950,"height":438,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=950%2C438&ssl=1"},"mh-magazine-content":{"file":"can-cuch-hotel-montseny-13-678x381.jpg","width":678,"height":381,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=678%2C381&ssl=1"},"mh-magazine-large":{"file":"can-cuch-hotel-montseny-13-678x509.jpg","width":678,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=678%2C509&ssl=1"},"mh-magazine-medium":{"file":"can-cuch-hotel-montseny-13-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=326%2C245&ssl=1"},"mh-magazine-small":{"file":"can-cuch-hotel-montseny-13-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?resize=80%2C60&ssl=1"},"full":{"file":"can-cuch-hotel-montseny-13.jpg?fit=950%2C713&ssl=1","width":950,"height":713,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg?fit=950%2C713&ssl=1"}},"image_meta":{"aperture":"2.4","credit":"","camera":"iPhone 5","caption":"","created_timestamp":"1395514843","copyright":"","focal_length":"4.12","iso":"64","shutter_speed":"0.025","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/locaacademiafamiliar.com\/wp-content\/uploads\/2016\/11\/can-cuch-hotel-montseny-13.jpg","_links":{"self":[{"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/media\/4944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/locaacademiafamiliar.com\/ca\/wp-json\/wp\/v2\/comments?post=4944"}]}}